{"id":189238,"date":"2026-07-13T11:04:02","date_gmt":"2026-07-13T15:04:02","guid":{"rendered":"https:\/\/linitiative.ca\/International\/7e-edition-des-competitions-inter-effors-les-kuilse-sadjugent-le-trophee-en-football\/"},"modified":"2026-07-13T11:04:02","modified_gmt":"2026-07-13T15:04:02","slug":"7e-edition-des-competitions-inter-effors-les-kuilse-sadjugent-le-trophee-en-football","status":"publish","type":"post","link":"https:\/\/linitiative.ca\/International\/7e-edition-des-competitions-inter-effors-les-kuilse-sadjugent-le-trophee-en-football\/","title":{"rendered":"7e \u00e9dition des comp\u00e9titions Inter-EFFORS\u00a0: Les Kuils\u00e9 s\u2019adjugent le troph\u00e9e en football"},"content":{"rendered":"<div class=\"td-post-featured-image\">\n<figure><a href=\"https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2.jpeg\" data-caption=\"\u00ab Durant toute une semaine, notre ville a v\u00e9cu au rythme du sport, de la fraternit\u00e9 et de l'excellence \u00bb, s'est r\u00e9joui le pr\u00e9sident de la d\u00e9l\u00e9gation sp\u00e9ciale de la commune de Fada N'Gourma, Kampadiba J\u00e9r\u00f4me Idani.\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"857\" class=\"entry-thumb td-modal-image\" src=\"https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2-696x857.jpeg\" srcset=\"https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2-696x857.jpeg 696w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2-244x300.jpeg 244w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2-832x1024.jpeg 832w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2-768x946.jpeg 768w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2-1248x1536.jpeg 1248w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2-341x420.jpeg 341w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2-150x185.jpeg 150w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2-300x369.jpeg 300w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2-324x400.jpeg 324w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2-1068x1315.jpeg 1068w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2.jpeg 1280w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" alt=\"\" title=\"4.JPG (2)\"\/><\/a><figcaption class=\"wp-caption-text\">\u00ab Durant toute une semaine, notre ville a v\u00e9cu au rythme du sport, de la fraternit\u00e9 et de l&rsquo;excellence \u00bb, s&rsquo;est r\u00e9joui le pr\u00e9sident de la d\u00e9l\u00e9gation sp\u00e9ciale de la commune de Fada N&rsquo;Gourma, Kampadiba J\u00e9r\u00f4me Idani.<\/figcaption><\/figure>\n<\/div>\n<p><strong>La 7<sup>e<\/sup> \u00e9dition des comp\u00e9titions Inter-Ecoles de formation pour la rel\u00e8ve sportive (Inter-EFFORS)<\/strong><strong>, organis\u00e9<\/strong><strong>e<\/strong> <strong>dans la ville de Fada N\u2019Gourma,<\/strong> <strong>s\u2019est<\/strong> <strong>achev\u00e9<\/strong><strong>e<\/strong><strong>, en apoth\u00e9ose,<\/strong><strong>\u00a0<\/strong><strong>avec<\/strong> <strong>la finale de la comp\u00e9tition de football<\/strong> <strong>jou\u00e9e<\/strong><strong>,<\/strong> <strong>dimanche<\/strong> <strong>12 juillet 2026<\/strong><strong>, dans la cuvette du stade<\/strong><strong>\u00a0<\/strong><strong>Nungu,<\/strong><strong>\u00a0<\/strong><strong>entre<\/strong><strong>\u00a0<\/strong><strong>les \u00e9quipes des Kuils\u00e9 et du Nakamb\u00e9.<\/strong> <strong>Au terme d\u2019une rencontre \u00e2prement disput\u00e9e<\/strong><strong>,<\/strong> <strong>l\u2019\u00e9quipe des Kuils\u00e9<\/strong> <strong>est venue \u00e0 bout de celle du Nakamb\u00e9 \u00e0 l\u2019issue de la s\u00e9ance des tirs au but, en pr\u00e9sence de la ministre en charge des Sports, Annick Lydie Djouma Pikbougoum.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Les rideaux sont tomb\u00e9s sur la 7e \u00e9dition des comp\u00e9titions Inter-Ecoles de formation pour la rel\u00e8ve sportive (Inter-EFFORS), organis\u00e9e du 6 au 12 juillet 2026, \u00e0 Fada N\u2019Gourma, sur le th\u00e8me : \u00ab Ensemble pour une rel\u00e8ve sportive saine et engag\u00e9e \u00bb. Point d\u2019orgue de cette 7e \u00e9dition des comp\u00e9titions Inter-EFFORS, la finale du tournoi de football qui a oppos\u00e9 les \u00e9quipes des Kuils\u00e9 et du Nakamb\u00e9, dimanche 12 juillet 2026, dans l\u2019enceinte du stade Nungu de Fada N\u2019Gourma. Disput\u00e9e en pr\u00e9sence de la ministre en charge des Sports, Annick Lydie Djouma Pikbougoum, ainsi que de plusieurs gouverneurs de r\u00e9gions, la rencontre a tenu toutes ses promesses. Tr\u00e8s entreprenants d\u00e8s l\u2019entame, les joueurs des Kuils\u00e9 ont multipli\u00e9 les offensives sans parvenir \u00e0 marquer. Contre le cours du jeu, le Nakamb\u00e9 a ouvert le score \u00e0 la 50e minute gr\u00e2ce \u00e0 Oualilou Nar\u00e9, auteur d\u2019un coup franc magistralement ex\u00e9cut\u00e9 au second poteau. Loin de se d\u00e9courager, les Kuils\u00e9 ont poursuivi leur domination et ont \u00e9t\u00e9 r\u00e9compens\u00e9s quatre minutes plus tard.<\/p>\n<figure id=\"attachment_165553\" aria-describedby=\"caption-attachment-165553\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.sidwaya.info\/7e-edition-des-competitions-inter-effors-les-kuilse-sadjugent-le-trophee-en-football\/2-jpg-2-7\/\" rel=\"attachment wp-att-165553\"><img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"165553\" data-permalink=\"https:\/\/www.sidwaya.info\/7e-edition-des-competitions-inter-effors-les-kuilse-sadjugent-le-trophee-en-football\/2-jpg-2-7\/\" data-orig-file=\"https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2.jpeg\" data-orig-size=\"2134,1413\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 750D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1783885483&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"2.JPG (2)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Pour la ministre en charge des Sports, Annick Lydie Djouma Pikbougoum, les EFFORS traduisent la volont\u00e9 du gouvernement de b\u00e2tir une \u00e9lite sportive comp\u00e9titive et performante.&lt;\/p&gt;\" data-large-file=\"https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2-1024x678.jpeg\" class=\"size-full wp-image-165553\" src=\"https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2.jpeg\" alt=\"\" width=\"2134\" height=\"1413\" srcset=\"https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2.jpeg 2134w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2-300x199.jpeg 300w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2-1024x678.jpeg 1024w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2-768x509.jpeg 768w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2-1536x1017.jpeg 1536w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2-2048x1356.jpeg 2048w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2-634x420.jpeg 634w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2-150x99.jpeg 150w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2-696x461.jpeg 696w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2-1068x707.jpeg 1068w, https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/2.JPG-2-1920x1271.jpeg 1920w\" sizes=\"(max-width: 2134px) 100vw, 2134px\"\/><\/a><figcaption id=\"caption-attachment-165553\" class=\"wp-caption-text\">Pour la ministre en charge des Sports, Annick Lydie Djouma Pikbougoum, les EFFORS traduisent la volont\u00e9 du gouvernement de b\u00e2tir une \u00e9lite sportive comp\u00e9titive et performante.<\/figcaption><\/figure>\n<p>Profitant d\u2019une h\u00e9sitation de l\u2019arri\u00e8re-garde adverse, le virevoltant Amidou Sodr\u00e9 a remis les deux \u00e9quipes \u00e0 \u00e9galit\u00e9. Malgr\u00e9 plusieurs occasions de part et d\u2019autre, le score est rest\u00e9 inchang\u00e9 au terme des deux p\u00e9riodes de 30 minutes. Il a donc fallu recourir \u00e0 la fatidique \u00e9preuve des tirs au but pour d\u00e9partager les deux formations. Plus adroits dans cet exercice, les Kuils\u00e9 se sont impos\u00e9s par quatre tirs r\u00e9ussis contre deux, d\u00e9crochant ainsi le troph\u00e9e de champion de cette 7e \u00e9dition en football. Les nouveaux champions ont re\u00e7u le troph\u00e9e ainsi que des m\u00e9dailles, tandis que le Nakamb\u00e9, finaliste malheureux, et le Goulmou, class\u00e9 troisi\u00e8me, ont \u00e9galement \u00e9t\u00e9 r\u00e9compens\u00e9s pour leurs performances.<\/p>\n<p><strong>Une rel\u00e8ve sportive prometteuse<\/strong><\/p>\n<p>En plus du football, les jeunes sportifs se sont affront\u00e9s pendant une semaine dans plusieurs disciplines, notamment le basketball, le handball, le volleyball, l\u2019athl\u00e9tisme, le cyclisme et la lutte traditionnelle. Selon le pr\u00e9sident de la commission technique, Bassedjona Gnanou, les r\u00e9sultats enregistr\u00e9s refl\u00e8tent le niveau des prestations fournies tout au long de la comp\u00e9tition. \u00ab Les meilleurs ont gagn\u00e9 \u00bb, a-t-il r\u00e9sum\u00e9. En handball, l\u2019\u00e9quipe A du Kadiogo s\u2019est adjug\u00e9 le troph\u00e9e. Le tournoi de volleyball a \u00e9t\u00e9 remport\u00e9 par l\u2019EFFORS des Tannouyan. En cyclisme, l\u2019\u00e9quipe C du Nakamb\u00e9 s\u2019est impos\u00e9e dans l\u2019\u00e9preuve du contre-la-montre par \u00e9quipe chez les gar\u00e7ons, tandis que l\u2019\u00e9quipe B de la m\u00eame r\u00e9gion a domin\u00e9 l\u2019\u00e9preuve f\u00e9minine. Dans les comp\u00e9titions individuelles de contre-la-montre, Ouimemda Mohamed chez les gar\u00e7ons et Limbon\u00e9 Nassiratou chez les filles se sont illustr\u00e9s en montant sur la plus haute marche du podium. Les deux athl\u00e8tes ont \u00e9galement confirm\u00e9 leur supr\u00e9matie en remportant les \u00e9preuves du crit\u00e9rium. En lutte traditionnelle, disput\u00e9e dans cinq cat\u00e9gories, l\u2019EFFORS du Bankui a dict\u00e9 sa loi.<\/p>\n<p>En athl\u00e9tisme, les honneurs sont revenus \u00e0 l\u2019EFFORS du Nazinon, class\u00e9e premi\u00e8re. Pour la ministre en charge des Sports, Annick Lydie Djouma Pikbougoum, patronne de l\u2019\u00e9v\u00e8nement, cette semaine de comp\u00e9titions aura \u00e9t\u00e9 un moment privil\u00e9gi\u00e9 de communion, d\u2019int\u00e9gration et de coh\u00e9sion entre les jeunes sportifs venus des diff\u00e9rentes r\u00e9gions du Burkina Faso. \u00ab Durant une semaine, les jeunes sportifs ont rivalis\u00e9 d\u2019ardeur pour offrir \u00e0 la capitale du Goulmou et au pays tout entier ce qu\u2019ils avaient de plus cher : effort, sueur, talent, d\u00e9passement de soi et fraternit\u00e9 \u00bb, a-t-elle d\u00e9clar\u00e9, avant de f\u00e9liciter les athl\u00e8tes qui se sont illustr\u00e9s. La ministre a rappel\u00e9 que les EFFORS, cr\u00e9\u00e9es en 2019, traduisent la volont\u00e9 du gouvernement de b\u00e2tir une \u00e9lite sportive comp\u00e9titive et performante, capable de porter haut les couleurs du Burkina Faso sur les sc\u00e8nes continentale et internationale. Elle a, par ailleurs, salu\u00e9 l\u2019engagement du comit\u00e9 d\u2019organisation et traduit sa reconnaissance \u00e0 toutes les personnes qui ont contribu\u00e9 au succ\u00e8s de cette \u00e9dition. Et, comme innovation cette ann\u00e9e, la camarade Pikbougoum a indiqu\u00e9 que les 733 jeunes sportifs, ont b\u00e9n\u00e9fici\u00e9 de s\u00e9ances de formation et de sensibilisation aux id\u00e9aux de la R\u00e9volution progressiste populaire (RPP), notamment le patriotisme, la solidarit\u00e9 et le vivre-ensemble.<\/p>\n<p><strong>Joanny SOW<\/strong><\/p>\n<p><strong>Kanlou SANDAMBA (Stagiaire)<\/strong><\/p>\n<p>Auteur: BH SIDWAYA<br \/>\n<a href=\"https:\/\/www.sidwaya.info\/7e-edition-des-competitions-inter-effors-les-kuilse-sadjugent-le-trophee-en-football\/\">Cliquez ici pour lire l&rsquo;article depuis sa source.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Durant toute une semaine, notre ville a v\u00e9cu au rythme du sport, de la fraternit\u00e9 et de l&rsquo;excellence \u00bb, s&rsquo;est r\u00e9joui le pr\u00e9sident de la d\u00e9l\u00e9gation sp\u00e9ciale de la commune de Fada N&rsquo;Gourma, Kampadiba J\u00e9r\u00f4me Idani. La 7e \u00e9dition des comp\u00e9titions Inter-Ecoles de formation pour la rel\u00e8ve sportive (Inter-EFFORS), organis\u00e9e dans la ville de [&hellip;]<\/p>\n","protected":false},"author":1816,"featured_media":189239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/www.sidwaya.info\/wp-content\/uploads\/2026\/07\/4.JPG-2.jpeg","fifu_image_alt":"7e \u00e9dition des comp\u00e9titions Inter-EFFORS\u00a0: Les Kuils\u00e9 s\u2019adjugent le troph\u00e9e en football","footnotes":""},"categories":[73,81],"tags":[],"class_list":["post-189238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-burkina-faso"],"_links":{"self":[{"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/posts\/189238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/users\/1816"}],"replies":[{"embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/comments?post=189238"}],"version-history":[{"count":0,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/posts\/189238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/media\/189239"}],"wp:attachment":[{"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/media?parent=189238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/categories?post=189238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/tags?post=189238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}