{"id":189344,"date":"2026-07-15T13:04:45","date_gmt":"2026-07-15T17:04:45","guid":{"rendered":"https:\/\/linitiative.ca\/International\/les-gardiens-des-phares-tunisiens-une-mission-essentielle-pour-la-securite-maritime\/"},"modified":"2026-07-15T13:04:45","modified_gmt":"2026-07-15T17:04:45","slug":"les-gardiens-des-phares-tunisiens-une-mission-essentielle-pour-la-securite-maritime","status":"publish","type":"post","link":"https:\/\/linitiative.ca\/International\/les-gardiens-des-phares-tunisiens-une-mission-essentielle-pour-la-securite-maritime\/","title":{"rendered":"Les gardiens des phares tunisiens: Une mission essentielle pour la s\u00e9curit\u00e9 maritime"},"content":{"rendered":"<p><strong>Kamel, 44 ans, est gardien de phare, fils de gardien de phare. L\u2019une des rares exceptions dans sa cat\u00e9gorie. Son p\u00e8re, Abdelmajid, avait pass\u00e9 38 ans de carri\u00e8re sur les \u00eeles de La Galite, Galiton Cani et Plane avant de finir par s\u2019installer \u00e0 Ras Angela.<\/strong><\/p>\n<p>Il prendra sa retraite en 2001. Kamel l\u2019avait suivi partout durant sa prime enfance, et quand il devait aller \u00e0 l\u2019\u00e9cole, il \u00e9tait \u00abdescendu\u00bb \u00e0 Tunis, aupr\u00e8s de ses grands-parents. Mais, aux moindres vacances, il revenait \u00e0 la maison, au bas d\u2019un phare. Cela a toujours \u00e9t\u00e9 son chez-lui. Recrut\u00e9 en tant que civil en 1990, il suivra les pas de son p\u00e8re, sur le m\u00eame parcours, et le voil\u00e0 aujourd\u2019hui gardien de phare \u00e0 Ras Angela.<\/p>\n<p>Taoufik, 42 ans, ma\u00eetre principal \u00e0 la Marine nationale, a \u00e9t\u00e9 lui aussi gardien de phare, mais y acc\u00e9dant par une autre voie: les \u00e9coles de formation. G\u00e9n\u00e9ralement, les recrues qui s\u2019engagent dans la carri\u00e8re militaire passent par l\u2019une de ces \u00e9coles, comme celle des quartiers ma\u00eetres \u00e0 Menzel Abderrahamen. A leur sortie, ceux qui optent pour les Phares &amp; Balises sont re\u00e7us dans un centre de formation sp\u00e9cialis\u00e9 o\u00f9 ils re\u00e7oivent une instruction sp\u00e9cifique de 3 \u00e0 4 mois leur permettant de s\u2019initier \u00e0 la signalisation maritime, le fonctionnement et l\u2019entretien des phares, notamment leurs optiques et les r\u00e8gles \u00e0 respecter. Commenceront alors pour eux des stages dans des phares isol\u00e9s, sur des \u00eeles. Ils y apprendront la vie dans un phare, du plus simple au plus exigeant. Vivre ensemble, travailler en \u00e9quipe, pr\u00e9parer le pain, conserver et utiliser \u00e0 bon escient les approvisionnements, demander ses provisions, organiser sa vie quotidienne, g\u00e9rer les impr\u00e9vus et respecter les consignes. En fait, son emploi du temps est bien charg\u00e9, tant il a de t\u00e2ches \u00e0 accomplir.<\/p>\n<p><span><span><strong>Tout est fourni<\/strong><\/span><\/span><\/p>\n<p>Autant la Marine est exigeante sur le travail demand\u00e9, autant elle veille sur le confort des gardiens de phare. Des logements enti\u00e8rement meubl\u00e9s sont mis \u00e0 leur disposition. Sur les \u00eeles isol\u00e9es, ce sont essentiellement des c\u00e9libataires, rarement de jeunes couples, avec des enfants non encore arriv\u00e9s \u00e0 l\u2019\u00e2ge de la scolarisation. A terre, c\u2019est mixte, des familles et des c\u00e9libataires. Jamais un gardien n\u2019est livr\u00e9 \u00e0 lui-m\u00eame, ils sont au moins deux, mais en fait quatre, voire cinq.<\/p>\n<p>L\u2019inventaire d\u2019un phare est int\u00e9ressant \u00e0 lire. Les maisons sont bien \u00e9quip\u00e9es: cuisini\u00e8res, frigos, cong\u00e9lateurs, chauffages, literie, draps et couvertures, postes t\u00e9l\u00e9, paraboles satellitaires, etc. Tout est fourni par l\u2019administration (le minist\u00e8re de la D\u00e9fense), des produits d\u2019entretien aux fournitures de bureau. Gr\u00e2ce au taux journalier am\u00e9lior\u00e9 octroy\u00e9 aux gardiens, ils peuvent passer commande de l\u2019approvisionnement de leur choix. Pour les phares isol\u00e9s, un ravitaillement est assur\u00e9 chaque mois.\u00a0 Il y a de tout: fruits et l\u00e9gumes, lait, p\u00e2tes alimentaires, conserves, eau min\u00e9rale, boissons gazeuses, jus, pain, etc. En pr\u00e9vision du mauvais temps qui emp\u00eacherait les op\u00e9rations de ravitaillement, il faut recourir \u00e0 la caisse de secours qui ne peut \u00eatre ouverte que sur autorisation. En effet, lors de chaque ravitaillement, on tire des produits d\u00e9j\u00e0 conserv\u00e9s dans cette caisse et on les remplace par les nouveaux produits arriv\u00e9s. Si on re\u00e7oit dix bo\u00eetes de concentr\u00e9 de tomates, on les place dans la caisse d\u2019o\u00f9 on retire autant de bo\u00eetes qui y avaient \u00e9t\u00e9 mises auparavant. Ainsi, la date limite de consommation est bien respect\u00e9e.<\/p>\n<p>Une pharmacie bien garnie est mise \u00e0 la disposition des gardiens de phare et de leurs familles. Outre les trousses de secours, elle contient divers m\u00e9dicaments de premiers soins. Les m\u00e9decins de garde peuvent \u00eatre consult\u00e9s \u00e0 distance. En cas d\u2019urgence, l\u2019\u00e9vacuation est organis\u00e9e par vedette, voire par h\u00e9licopt\u00e8re.<\/p>\n<p><em>\u00abOn finit par prendre le rythme, explique un gardien de phare. Pendant les dix premiers jours, on profite des l\u00e9gumes frais re\u00e7us pour faire la cuisine. Puis, on se rabat pendant les vingt jours suivants sur les p\u00e2tes et les conserves. On s\u2019organise en cons\u00e9quence. Sur nombre d\u2019\u00eeles, il est tr\u00e8s difficile de cultiver des l\u00e9gumes, la terre est rocheuse et le vent ne laisse rien pousser. Mais \u00e0 terre, on peut \u00eatre mieux loti et avoir des potagers\u00bb<\/em>.\u00a0 \u00a0Dans l\u2019inventaire, il y a aussi la bo\u00eete \u00e0 outils : tout ce qu\u2019il faut pour le bricolage, l\u2019entretien \u00e9lectrique et m\u00e9canique, la menuiserie, la plomberie, la soudure, la peinture, les optiques, tout&#8230;<\/p>\n<p><span><span><strong>Des \u00e9quipes solitaires, mais solidaires<\/strong><\/span><\/span><\/p>\n<p>Faut-il une \u00e9quipe si fournie? <em>\u00abOui, on doit \u00eatre au moins quatre pour pouvoir jouer une partie de cartes, nous r\u00e9pond un gardien sur le ton de la boutade, mais la vraie raison est facile \u00e0 comprendre. Le r\u00e9gime de travail nous accorde une belle r\u00e9cup\u00e9ration pour un mois en poste. Alors avec les cong\u00e9s et les r\u00e9cup\u00e9rations, on est souvent \u00e0 quatre. Mais, les t\u00e2ches sont nombreuses. Il faut se relayer nuit et jour, sans discontinuit\u00e9, et veiller \u00e0 ce que le phare soit toujours allum\u00e9 de nuit. Il y a aussi toutes les t\u00e2ches d\u2019entretien de l\u2019optique, de la machinerie, et des b\u00e2timents. Les phares sont tr\u00e8s expos\u00e9s aux ph\u00e9nom\u00e8nes climatiques et aux effets de la mer. Nous devons tout le temps lutter contre la corrosion, repeindre, r\u00e9parer et veiller \u00e0 la bonne tenue de l\u2019ensemble\u00bb.<\/em><\/p>\n<p><em>\u00abDans la nuit, c\u00f4toyant les dangers, le marin a besoin de votre feu, rappelle le manuel remis aux agents de phares. Votre feu doit r\u00e9aliser exactement son caract\u00e8re propre, sinon le marin risquerait de le confondre avec un autre feu. Vous auriez organis\u00e9 la catastrophe!\u00bb<\/em>. Tout doit alors \u00eatre nickel: les glaces de la lanterne et les anneaux de l\u2019optique doivent \u00eatre nettoy\u00e9s de mani\u00e8re \u00e0 briller comme du cristal. Le rythme des lumi\u00e8res doit \u00eatre exact, sans jamais varier, etc.<\/p>\n<p>C\u2019est un m\u00e9tier qui est fond\u00e9 sur la comp\u00e9tence, l\u2019exp\u00e9rience et l\u2019amour du m\u00e9tier, avec un sens aigu des responsabilit\u00e9s, l\u2019esprit d\u2019initiative et celui de l\u2019observation, avec m\u00e9thode et dans l\u2019ordre. Chaque d\u00e9tail compte. L\u2019amour du m\u00e9tier? Kamel, qui a h\u00e9rit\u00e9 de son p\u00e8re cette \u00abmission\u00bb de gardien de phare, compte-t-il la transmettre \u00e0 ses enfants? \u00abS\u2019ils en veulent! r\u00e9pond-il sans grand espoir. Mais d\u2019autres jeunes prendront le relais s\u00fbrement!\u00bb Les phares, c\u2019est plus qu\u2019une mission, c\u2019est une passion, affirment tous ceux qui sont dans les Phares et Balises.<\/p>\n<p><strong>Lire aussi<\/strong><\/p>\n<p><a href=\"https:\/\/www.leaders.com.tn\/article\/38260-thyna-premier-phare-en-beton-jamais-construit-sur-la-planete\" target=\"_blank\">Thyna: Premier phare en b\u00e9ton jamais construit sur la plan\u00e8te<\/a><\/p>\n<p><a href=\"https:\/\/www.leaders.com.tn\/article\/38254-comment-la-tunisie-a-eclaire-ses-cotes-pour-securiser-la-navigation-en-mediterranee\" target=\"_blank\">Comment la Tunisie a \u00e9clair\u00e9 ses c\u00f4tes pour s\u00e9curiser la navigation en M\u00e9diterran\u00e9e<\/a><\/p>\n<p><a href=\"https:\/\/www.leaders.com.tn\/article\/38246-etablissements-de-signalisation-maritime-qu-ils-soient-isoles-ou-au-coeur-des-medinas-chacun-a-son-charme\" target=\"_blank\">\u00c9tablissements de signalisation maritime : Qu&rsquo;ils soient isol\u00e9s ou au c\u0153ur des m\u00e9dinas, chacun a son charme<\/a><\/p>\n<p><a href=\"https:\/\/www.leaders.com.tn\/article\/38231-le-patrimoine-maritime-de-la-tunisie-les-magnifiques-phares-de-ses-cotes\" target=\"_blank\">Le patrimoine maritime de la Tunisie: les magnifiques phares de ses c\u00f4tes<\/a><br \/>\u00a0<\/p>\n<p>Auteur:<br \/>\n<a href=\"https:\/\/www.leaders.com.tn\/article\/38269-les-gardiens-des-phares-tunisiens-une-mission-essentielle-pour-la-securite-maritime\">Cliquez ici pour lire l&rsquo;article depuis sa source.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kamel, 44 ans, est gardien de phare, fils de gardien de phare. L\u2019une des rares exceptions dans sa cat\u00e9gorie. Son p\u00e8re, Abdelmajid, avait pass\u00e9 38 ans de carri\u00e8re sur les \u00eeles de La Galite, Galiton Cani et Plane avant de finir par s\u2019installer \u00e0 Ras Angela. Il prendra sa retraite en 2001. Kamel l\u2019avait suivi [&hellip;]<\/p>\n","protected":false},"author":1772,"featured_media":189345,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/www.leaders.com.tn\/uploads\/content\/thumbnails\/178412148715_content.jpg","fifu_image_alt":"Les gardiens des phares tunisiens: Une mission essentielle pour la s\u00e9curit\u00e9 maritime","footnotes":""},"categories":[73,55],"tags":[],"class_list":["post-189344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-tunisie"],"_links":{"self":[{"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/posts\/189344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/users\/1772"}],"replies":[{"embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/comments?post=189344"}],"version-history":[{"count":0,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/posts\/189344\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/media\/189345"}],"wp:attachment":[{"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/media?parent=189344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/categories?post=189344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/tags?post=189344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}