{"id":189352,"date":"2026-07-15T13:19:41","date_gmt":"2026-07-15T17:19:41","guid":{"rendered":"https:\/\/linitiative.ca\/International\/le-groupe-immobilier-belge-macan-poursuit-ses-investissements-au-maroc\/"},"modified":"2026-07-15T13:19:41","modified_gmt":"2026-07-15T17:19:41","slug":"le-groupe-immobilier-belge-macan-poursuit-ses-investissements-au-maroc","status":"publish","type":"post","link":"https:\/\/linitiative.ca\/International\/le-groupe-immobilier-belge-macan-poursuit-ses-investissements-au-maroc\/","title":{"rendered":"Le groupe immobilier belge MACAN poursuit ses investissements au Maroc"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Onze ans apr\u00e8s y avoir pris pied, le groupe immobilier belge Macan Development \u00e9largit son champ d\u2019intervention au Maroc. En effet, cet acteur de r\u00e9f\u00e9rence sur le march\u00e9 de la construction, mais aussi de la gestion locative et du conseil immobilier, vient de lancer son premier projet immobilier en dehors de Marrakech, la ville qui l\u2019a vu r\u00e9aliser et livrer ses premiers faits d\u2019armes dans notre pays.<\/strong><\/p>\n<p class=\"wp-block-paragraph\">Et c\u2019est dans le quartier administratif de la capitale politique que Macan Development a jet\u00e9 son d\u00e9volu pour y \u00e9riger un immeuble R+5 \u00e0 usage r\u00e9sidentiel haut de gamme. Limit\u00e9e \u00e0 une cinquantaine de millions de dirhams et totalisant \u00e0 peine une vingtaine d\u2019unit\u00e9s \u00e0 commercialiser, l\u2019enveloppe d\u2019investissement de ce projet fait partie d\u2019un programme ambitieux annonc\u00e9 en 2024 par le pr\u00e9sident du groupe Macan, Philippe Guillion, et qui totalise pr\u00e8s de 1,5 milliard de dirhams au cours des cinq prochaines ann\u00e9es, apr\u00e8s les 600 millions de dirhams d\u00e9j\u00e0 investis \u00e0 Marrakech.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Lire aussi | <a href=\"https:\/\/www.challenge.ma\/ofppt-et-tgcc-un-partenariat-strategique-pour-renforcer-les-competences-dans-le-btp-322256\/\">OFPPT et TGCC : un partenariat strat\u00e9gique pour renforcer les comp\u00e9tences dans le BTP<\/a><\/strong><\/p>\n<p class=\"wp-block-paragraph\">Outre Rabat, o\u00f9 Macan Development vient d\u2019inaugurer ses op\u00e9rations en partenariat avec l\u2019entreprise de BTP K Stone Construction, ce groupe, qui nourrit de grandes ambitions au Maroc, lorgne d\u2019autres villes cl\u00e9s comme Agadir, K\u00e9nitra et Dakhla, o\u00f9 il scrute actuellement plusieurs opportunit\u00e9s d\u2019investissement sur diff\u00e9rents segments (notamment ceux du r\u00e9sidentiel, des bureaux et du commercial).<\/p>\n<p class=\"wp-block-paragraph\">Rappelons que le groupe belge Macan est compos\u00e9 de plusieurs soci\u00e9t\u00e9s, organis\u00e9es sous la holding Macan Group. Il s\u2019agit de Macan Development en Belgique et au Maroc (d\u00e9veloppement de biens destin\u00e9s \u00e0 la vente, dont Macananda 2, l\u2019entit\u00e9 qui porte le projet de Rabat), Macan Properties (gestion de biens mis en location), Sotheby\u2019s Real Estate Morocco et Belgium (conseil et agence immobili\u00e8re) et Castell Management (property management de biens pour des tiers).<\/p>\n<p>Auteur: Rachid Boutaleb<br \/>\n<a href=\"https:\/\/www.challenge.ma\/le-groupe-immobilier-belge-macan-poursuit-ses-investissements-au-maroc-322272\/\">Cliquez ici pour lire l&rsquo;article depuis sa source.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Onze ans apr\u00e8s y avoir pris pied, le groupe immobilier belge Macan Development \u00e9largit son champ d\u2019intervention au Maroc. En effet, cet acteur de r\u00e9f\u00e9rence sur le march\u00e9 de la construction, mais aussi de la gestion locative et du conseil immobilier, vient de lancer son premier projet immobilier en dehors de Marrakech, la ville qui [&hellip;]<\/p>\n","protected":false},"author":1787,"featured_media":189353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/www.challenge.ma\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-15-a-12.15.41.png","fifu_image_alt":"Le groupe immobilier belge MACAN poursuit ses investissements au Maroc","footnotes":""},"categories":[78,54],"tags":[],"class_list":["post-189352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","category-maroc"],"_links":{"self":[{"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/posts\/189352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/users\/1787"}],"replies":[{"embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/comments?post=189352"}],"version-history":[{"count":0,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/posts\/189352\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/media\/189353"}],"wp:attachment":[{"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/media?parent=189352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/categories?post=189352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/linitiative.ca\/International\/wp-json\/wp\/v2\/tags?post=189352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}